{"id":234,"date":"2015-09-05T08:17:50","date_gmt":"2015-09-05T06:17:50","guid":{"rendered":"http:\/\/web6304.softwerk25.konto.name\/international\/?p=234"},"modified":"2018-08-06T10:29:35","modified_gmt":"2018-08-06T08:29:35","slug":"internationale-muensterlaenderpruefung-2015-in-tschechien-um-ivancice","status":"publish","type":"post","link":"https:\/\/klm-international.info\/de\/internationale-muensterlaenderpruefung-2015-in-tschechien-um-ivancice\/","title":{"rendered":"Internationale M\u00fcnsterl\u00e4nderpr\u00fcfung 2015 in Tschechien um Ivan\u010dice"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>In diesem Jahr hat der Klub f\u00fcr Langhaarige Vorstehhunde Tschechien (Klub dlouhosrstych oharu) zur Internationalen M\u00fcnsterl\u00e4nderpr\u00fcfung am 05.\/06.09.2015 um Ivan\u010dice (in der N\u00e4he von Brun) eingeladen. Parallel fand die IVGP statt, an der acht Hunde teilnahmen.<\/p>\n<p>Zun\u00e4chst traf sich am 04.09.2015 das Pr\u00e4sidium von KlM-I. Im Anschluss an die Sitzung fand eine Zuchtschau im Suchenlokal auf dem Schlossinnenhof statt.<\/p>\n<p>Zur IMP sind 5 Kleine M\u00fcnsterl\u00e4nder und ein Gro\u00dfer M\u00fcnsterl\u00e4nder angetreten. Besonders zu erw\u00e4hnen ist, dass ein Kleiner M\u00fcnsterl\u00e4nder extra aus Japan angereist war. Zwei KlM kamen aus Deutschland und zwei KlM sowie ein GM aus Tschechien. Alle teilnehmenden Hunde hatten sich f\u00fcr die IMP-B angemeldet.<\/p>\n<p>Nach der Begr\u00fc\u00dfung im Schlosshof Hrubsice ging es f\u00fcr die Teilnehmer der IMP in das sehr gut mit Hasen besetzte Feldrevier. Hier konnten die teilnehmenden Hunde ihre Anlagen im Feld in zwei, mit internationalen Richtern besetzten Gruppen, unter Beweis stellen. Vor Ort war f\u00fcr reichlich Verpflegung gesorgt.<\/p>\n<p>Am Nachmittag wurde zum Wasser umgesetzt. Es handelte sich um ein gro\u00dfes Gew\u00e4sser mit gro\u00dfen Schilfpartien.<\/p>\n<p>Den Abend verbrachte man festlich mit allen Teilnehmern, Richtern und Organisatoren der IMP und der IVGP im Rittersaal des Schlosses mit Kn\u00f6deln, Sauerkraut und Schweinefleisch und Bier. Als Nachtisch spendete der Klub f\u00fcr Langhaarige Vorstehhunde Tschechien ein k\u00f6stliches Spanferkel. F\u00fcr Musik war ebenfalls gesorgt.<\/p>\n<p>Der zweite Teil der IMP wurde am Sonntagmorgen im Wald absolviert. Gro\u00df war die \u00dcberraschung, dass auch hier wieder f\u00fcr reichlich Verpflegung gesorgt war.<\/p>\n<p>Alle sechs Hunde haben die IMP-B bestanden. Suchensieger wurde mit 455 Punkten Tom\u00e1\u0161 Z\u00eddek mit seiner KlM H\u00fcndin Tamesis Eben-Ezer aus Tschechien. Die H\u00fcndin war als j\u00fcngster Hund bester Feld- und bester Waldhund. Bester Wasserhund wurde Crusoe Badaine, gef\u00fchrt von Dr. Arifumi Takazawa aus Japan.<\/p>\n<p>Die IMP hat wieder einmal zum internationalen Austausch beigetragen und Sprachbarrieren wurden ohne gro\u00dfe Schwierigkeiten \u00fcberwunden.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pr\u00fcfungsergebnisse<\/strong><\/p>\n<ol>\n<li>Tamesis Eben-Ezer (KlM), Tom\u00e1\u0161 Z\u00eddek (CZ), 455 Punkte<\/li>\n<li>Adar z Hol\u00e1sek (KlM), Roman Sobodka (CZ), 455 Punkte<\/li>\n<li>Orson Svatoborsk\u00dd (GM), Bc. Zuzana Fialov\u00e1 (CZ), 428 Punkte<\/li>\n<li>Crusoe Badaine (KlM), Dr. Arifumi Takazawa (Japan), 405 Punkte<\/li>\n<li>Gangster von der Rehbr\u00fcgge (KlM), Hermann Schl\u00e4pfer (D), 394 Punkte<\/li>\n<li>Anne von Burg Redinghoven (KlM), Hendrik Herr (D), 380 Punkte<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; In diesem Jahr hat der Klub f\u00fcr Langhaarige Vorstehhunde Tschechien (Klub dlouhosrstych oharu) zur Internationalen M\u00fcnsterl\u00e4nderpr\u00fcfung am 05.\/06.09.2015 um Ivan\u010dice (in der N\u00e4he von Brun) eingeladen. Parallel fand die IVGP statt, an der acht Hunde teilnahmen. Zun\u00e4chst traf sich am 04.09.2015 das Pr\u00e4sidium von KlM-I. Im Anschluss an die Sitzung fand eine Zuchtschau im [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-234","post","type-post","status-publish","format-standard","hentry","category-berichte-der-imp"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:23:06","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/posts\/234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/comments?post=234"}],"version-history":[{"count":3,"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/posts\/234\/revisions"}],"predecessor-version":[{"id":237,"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/posts\/234\/revisions\/237"}],"wp:attachment":[{"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/media?parent=234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/categories?post=234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/klm-international.info\/de\/wp-json\/wp\/v2\/tags?post=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}